{"id":1054,"date":"2020-11-04T01:57:03","date_gmt":"2020-11-04T01:57:03","guid":{"rendered":"http:\/\/redconsultingus.com\/blog\/?p=1054"},"modified":"2021-02-26T13:07:24","modified_gmt":"2021-02-26T13:07:24","slug":"case-de-sucesso-ultramedic","status":"publish","type":"post","link":"http:\/\/redconsultingus.com\/blog\/case-de-sucesso-ultramedic\/","title":{"rendered":"Case de Sucesso: Ultramedic"},"content":{"rendered":"\n<p>Criada em 2002, em Porto Alegre, Rio Grande do Sul, a <a href=\"https:\/\/www.ultramedic.com.br\/pt\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener nofollow\">Ultramedic<\/a> \u00e9 uma empresa especializada em equipamentos veterin\u00e1rios de diagn\u00f3stico por imagem. J\u00e1 s\u00e3o quase duas d\u00e9cadas sendo refer\u00eancia no ramo e crescendo como nunca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A decis\u00e3o de expandir<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Case de Sucesso - Samir Farah Ultramedic USA |  EP1\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/tqOhdPClUgM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Em 2019, Samir Farah, CEO da Ultramedic, viu na internacionaliza\u00e7\u00e3o de sua empresa uma oportunidade de diversificar suas receitas. <\/p>\n\n\n\n<p>Desse modo, fez sentido para Samir dar esse pr\u00f3ximo passo. <\/p>\n\n\n\n<p>N\u00e3o depender financeiramente apenas do Brasil, mesmo que a Ultramedic estivesse crescendo cada vez mais no pa\u00eds.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A escolha pela Red<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;<em>\u00c9 imposs\u00edvel internacionalizar uma empresa sozinho. Por isso, comecei a pesquisar empresas que pudessem me auxiliar com esse sonho e, e<\/em>ntre v\u00e1rias empresas<em>, a Red me deu o retorno mais r\u00e1pido.<\/em>&#8221; &#8211; <strong>Samir Farah<\/strong><\/p><\/blockquote>\n\n\n\n<p>A primeira impress\u00e3o \u00e9 a que fica. Pensando nisso, a Red Consulting d\u00e1 o seu melhor pra que, j\u00e1 no primeiro contato conosco, os clientes tirem toda e qualquer d\u00favida que tenham.<\/p>\n\n\n\n<p>Com a Ultramedic n\u00e3o foi diferente, o que foi fundamental para dar seguran\u00e7a ao Samir em colocar esse processo t\u00e3o importante em nossas m\u00e3os.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Abrir uma empresa nos EUA \u00e9 um desafio muito grande. Seja pela cultura ou idiomas diferentes. Por isso, escolhi quem realmente entende do assunto.&#8221; &#8211; <strong>Samir Farah<\/strong><\/p><\/blockquote>\n\n\n\n<p>Realmente, n\u00e3o \u00e9 um processo f\u00e1cil, mas com o suporte certo, ele com certeza se torna mais traquilo.<\/p>\n\n\n\n<p>A Red Consulting coloca a seguran\u00e7a e a responsabilidade em primeiro lugar para o seu sonho se torne realidade.<\/p>\n\n\n\n<p>A Ultramedic \u00e9 uma das 300 empresas e pessoas que que a Red auxiliou a dar o pr\u00f3ximo grande passo rumo aos Estados Unidos.<\/p>\n\n\n\n<p>Mais um case de sucesso que mostra o qu\u00e3o comprometidos somos em realizar sonhos e temos muito orgulho disso. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redconsultingus.com\/consultoria\/?utm_source=blog&amp;utm_medium=consultoria-vip&amp;utm_content=case-de-sucesso-ultramedic\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"210\" src=\"http:\/\/redconsultingus.com\/blog\/wp-content\/uploads\/2019\/10\/CTA-_consultoria-vip.jpg\" alt=\"Ultramedic\" class=\"wp-image-536\" srcset=\"http:\/\/redconsultingus.com\/blog\/wp-content\/uploads\/2019\/10\/CTA-_consultoria-vip.jpg 750w, http:\/\/redconsultingus.com\/blog\/wp-content\/uploads\/2019\/10\/CTA-_consultoria-vip-300x84.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/figure>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Criada em 2002, em Porto Alegre, Rio Grande do Sul, a Ultramedic \u00e9 uma empresa especializada em equipamentos veterin\u00e1rios de diagn\u00f3stico por imagem. J\u00e1 s\u00e3o quase duas d\u00e9cadas sendo refer\u00eancia no ramo e crescendo como &#8230; <a title=\"Case de Sucesso: Ultramedic\" class=\"read-more\" href=\"http:\/\/redconsultingus.com\/blog\/case-de-sucesso-ultramedic\/\" aria-label=\"More on Case de Sucesso: Ultramedic\">Ler Mais<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[939,924],"class_list":["post-1054","post","type-post","status-publish","format-standard","hentry","category-blog","tag-case-de-sucesso","tag-pt","no-featured-image-padding"],"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/posts\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":0,"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/posts\/1054\/revisions"}],"wp:attachment":[{"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/categories?post=1054"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/redconsultingus.com\/blog\/wp-json\/wp\/v2\/tags?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}